{"id":52565,"date":"2013-10-03T22:31:50","date_gmt":"2013-10-03T22:31:50","guid":{"rendered":"https:\/\/gerdtestpress.online\/?p=52565"},"modified":"2019-02-21T12:19:09","modified_gmt":"2019-02-21T12:19:09","slug":"my-guest-post-at-the-guardian-why-advertisers-should-back-a-global-digital-bill-of-rights","status":"publish","type":"post","link":"https:\/\/futuristgerd.com\/pt\/2013\/10\/my-guest-post-at-the-guardian-why-advertisers-should-back-a-global-digital-bill-of-rights\/","title":{"rendered":"O meu post como convidado no The Guardian: Porque \u00e9 que os anunciantes devem apoiar uma Carta dos Direitos Digitais a n\u00edvel mundial"},"content":{"rendered":"<p>At\u00e9 \u00e0 pr\u00f3xima <a href=\"https:\/\/www.theguardian.com\/media-network\/2013\/jul\/11\/changing-advertising-summit-2013-programme\" target=\"_blank\">Cimeira de Publicidade do Guardian, ter\u00e7a-feira, em Londres <\/a>(8 de outubro de 2013), onde farei o discurso de encerramento como parte de um painel de discuss\u00e3o para o qual fui convidado <a href=\"https:\/\/www.theguardian.com\/media-network\/media-network-blog\/2013\/oct\/03\/advertisers-digital-bill-of-rights\" target=\"_blank\">contribuir com um post convidado para o The Guardian<\/a> que, por acaso, \u00e9 a minha organiza\u00e7\u00e3o noticiosa de l\u00edngua inglesa favorita e tamb\u00e9m o meu recurso global. A sua cobertura do caso Snowden \/ NSA \u00e9 absolutamente impressionante, corajosa e ousada, e estou encantado por poder contribuir para este debate.  O meu post de convidado fala sobre como estes <a href=\"https:\/\/twitter.com\/search?src=typd&q=%23datawars\" target=\"_blank\"><strong>Datawars<\/strong><\/a> (como lhes chamo) e o neg\u00f3cio da publicidade est\u00e3o muito interligados.<\/p>\n<p>Aqui est\u00e3o os primeiros par\u00e1grafos (o resto \u00e9 <a href=\"https:\/\/www.theguardian.com\/media-network\/media-network-blog\/2013\/oct\/03\/advertisers-digital-bill-of-rights\" target=\"_blank\">aqui<\/a>):<\/p>\n<p>\"Acredito que os grandes volumes de dados se est\u00e3o a tornar a for\u00e7a motriz da nossa economia global e que ir\u00e3o conduzir a um novo tipo de guerra. Os publicit\u00e1rios precisam deles para direcionar os consumidores. Os governos e as autoridades policiais <a title=\"Mais do guardian.co.uk sobre Ag\u00eancias\" href=\"https:\/\/www.theguardian.com\/media-network\/agencies\">ag\u00eancias<\/a> precisamos dele para nos mantermos seguros e protegidos, <a title=\"\" href=\"https:\/\/www.theguardian.com\/world\/2013\/jun\/12\/edward-snowden-hong-kong-live\">assim se diz<\/a>. Plataformas de Internet e empresas de tecnologia, ou o \"<a title=\"\" href=\"https:\/\/www.theguardian.com\/books\/2013\/mar\/03\/who-owns-future-jaron-lanier-review\">servidores de sirenes<\/a>\", como Jaron Lanier lhes chama no seu \u00faltimo livro, precisam dela para manterem o seu papel fundamental nas nossas vidas digitais e para continuarem a alimentar-nos com todos aqueles fant\u00e1sticos servi\u00e7os, aplica\u00e7\u00f5es e plataformas gratuitas de que j\u00e1 n\u00e3o conseguimos prescindir.<\/p>\n<p><strong>Os consumidores: Os acordos faustianos j\u00e1 n\u00e3o existem?<\/strong><br \/>\nNa mente da maioria dos consumidores digitais, que anseiam por um fluxo constante de novas ofertas fixes que, por defeito, t\u00eam de ser gratuitas, \"pagar com dados\" e, por conseguinte, tornar-se invariavelmente o pr\u00f3prio conte\u00fado ou produto, tornou-se o novo normal - at\u00e9 agora. O que parecia ser um acordo algo razo\u00e1vel (\"Eu uso-te e tu usas-me\") come\u00e7a agora a parecer um para\u00edso de tolos: o nosso amor ilimitado e a nossa admira\u00e7\u00e3o vertiginosa pelo Gmail, pelo Google Docs e pela Pesquisa ou pelo sistema operativo Android, por exemplo, foram de facto silenciosamente convertidos em alimento para \"colecionar tudo\" <a title=\"\" href=\"https:\/\/www.theguardian.com\/commentisfree\/2013\/sep\/15\/nsa-mind-keith-alexander-star-trek\">Pretendentes a Capit\u00e3o Kirk<\/a> que anseiam pela superioridade da informa\u00e7\u00e3o sob o disfarce da seguran\u00e7a nacional.<\/p>\n<p>As recentes revela\u00e7\u00f5es do denunciante da NSA, Edward Snowden, est\u00e3o a tornar-se cada vez mais alucinantes, parecendo muitas vezes cita\u00e7\u00f5es de um romance de fic\u00e7\u00e3o cient\u00edfica de Cory Doctorow. As informa\u00e7\u00f5es libertadas por Edward mostraram ao mundo que este neg\u00f3cio faustiano dos meus dados privados em troca de coisas gratuitas j\u00e1 criou, de facto, um monstro global que est\u00e1 agora a emergir como um <a title=\"\" href=\"https:\/\/top50sf.files.wordpress.com\/2011\/07\/7ca0fa3225.jpg\">Godzilla zangado<\/a> da Ba\u00eda de T\u00f3quio. Vendemos os nossos dados e torn\u00e1mo-nos o conte\u00fado, ou seja, o produto, n\u00f3s pr\u00f3prios - e agora n\u00e3o temos qualquer controlo sobre nada disso. \u00c9 pegar ou largar, calar ou calar. Escolher <a title=\"\" href=\"https:\/\/www.huffingtonpost.com\/2013\/06\/07\/obama-defends-nsa_n_3406448.html\">privacidade ou seguran\u00e7a<\/a>. Ame-o ou deixe-o.<\/p>\n<p><strong>Epicentre USA: quebra de confian\u00e7a \u00e0 escala mundial<\/strong><br \/>\nComo diz Yochai Benkler, de Harvard <a title=\"\" href=\"https:\/\/www.theguardian.com\/commentisfree\/2013\/sep\/13\/nsa-behemoth-trampling-rights\">corretamente apontado<\/a> num brilhante guest post do Guardian, a NSA j\u00e1 declarou sozinha um novo tipo de guerra \u00e0 Internet tal como a conhecemos, mas, ao mesmo tempo, as nossas vidas digitais hiper-redeadas est\u00e3o agora t\u00e3o fortemente baseadas no pressuposto de que os mecanismos b\u00e1sicos de confian\u00e7a, permiss\u00e3o e controlo est\u00e3o a funcionar. Acontecimentos como este est\u00e3o a abalar essas cren\u00e7as at\u00e9 ao \u00e2mago. Os dados s\u00e3o o novo petr\u00f3leo, a confian\u00e7a \u00e9 a nova moeda - e quando a confian\u00e7a \u00e9 quebrada, o neg\u00f3cio tamb\u00e9m quebra rapidamente. A quest\u00e3o que se coloca \u00e9: quem precisa de petr\u00f3leo quando n\u00e3o h\u00e1 carros ou avi\u00f5es que funcionem com ele?<\/p>\n<p><strong>Imagine ser desconectado pelo e do consumidor: o fim dos cookies ser\u00e1 a menor das consequ\u00eancias<\/strong><br \/>\nImaginemos um cen\u00e1rio em que uma parte significativa dos futuros quatro mil milh\u00f5es de utilizadores da Internet come\u00e7a a questionar o acordo faustiano padr\u00e3o de \"os meus dados privados em troca da vossa conetividade, das vossas plataformas fixes e tecnologias fant\u00e1sticas\". Isto poderia significar o fim de quaisquer metodologias de rastreio significativas e normalizadas, com os utilizadores a deixarem de transmitir avidamente as suas localiza\u00e7\u00f5es e endere\u00e7os MAC nos seus dispositivos m\u00f3veis, bem como a prov\u00e1vel rejei\u00e7\u00e3o das tecnologias NFC\/RFID ou de qualquer tipo de dinheiro digital, por mais aliciante que um fornecedor ansioso o torne.<\/p>\n<p>Imaginemos que as marcas querem fazer publicidade a milhares de milh\u00f5es de utilizadores (tamb\u00e9m conhecidos como consumidores) em movimento ascendente e prontos a comprar, mas n\u00e3o t\u00eam autoriza\u00e7\u00e3o para saber o suficiente sobre quem s\u00e3o realmente, o que pensam e como chegar at\u00e9 eles de forma eficiente. Imagine que as marcas e os anunciantes n\u00e3o conseguem chegar aos consumidores porque n\u00e3o confiam nos meios de comunica\u00e7\u00e3o que podem utilizar para nos contactar e, por conseguinte, desconfiam deles. Imagine que os consumidores querem estar \"fora da grelha\" e fora do radar porque estar na grelha \u00e9 como andar nu pela Madison Avenue.<\/p>\n<p>Achas que isto n\u00e3o vai acontecer? Aparentemente, um quinto dos utilizadores de Internet de secret\u00e1ria do mundo <a title=\"\" href=\"https:\/\/qz.com\/120797\/over-one-fifth-of-people-use-ad-blocking-software-and-its-beginning-to-hurt\/\">j\u00e1 utilizam software de bloqueio de an\u00fancios<\/a> com os seus browsers. A Mozilla quer tornar a op\u00e7\u00e3o \"n\u00e3o rastrear\" a predefini\u00e7\u00e3o no Firefox, e muitos utilizadores experientes est\u00e3o agora a considerar <a title=\"\" href=\"https:\/\/www.pcworld.com\/article\/2048268\/schneier-on-nsas-encryption-defeating-efforts-trust-no-one.html\">a\u00e7\u00e3o ainda mais dram\u00e1tica<\/a> para se camuflarem e escaparem \u00e0 recolha global de dados e ao hiper-marketing que parece ter-se tornado uma mentalidade padr\u00e3o em muitos pa\u00edses. Jeff Jarvis tem raz\u00e3o quando diz que precisamos de <a title=\"\" href=\"https:\/\/www.theguardian.com\/commentisfree\/2013\/aug\/07\/big-tech-protect-big-brother\">Big Tech para nos defender do Big Brother<\/a>mas e se o Grande Irm\u00e3o for casado com a Grande Tecnologia...\".\u00a0 <a href=\"https:\/\/www.theguardian.com\/media-network\/media-network-blog\/2013\/oct\/03\/advertisers-digital-bill-of-rights\" target=\"_blank\">Ler mais no The Guardian<\/a><\/p>\n<p>Descarregue o PDF com a publica\u00e7\u00e3o completa do Guardian: <a href=\"https:\/\/futuristgerd.com\/old_lib\/2013\/10\/Why-advertisers-should-back-a-global-Digital-Bill-of-Rights-Media-Network-Guardian-Professional.pdf\">Porque \u00e9 que os anunciantes devem apoiar uma Declara\u00e7\u00e3o de Direitos Digital global | Media Network | Guardian Professional Vers\u00e3o PDF<\/a><\/p>\n<p><a href=\"https:\/\/www.theguardian.com\/media-network\/2013\/jul\/11\/changing-advertising-summit-2013-programme\" target=\"_blank\">Junte-se a mim na Cimeira de Londres <\/a>8 de outubro de 2013<\/p>\n<p><strong>Posts relacionados<\/strong><\/p>\n<p>Leia os meus coment\u00e1rios anteriores sobre Snowden \/ PRISM e as revela\u00e7\u00f5es da NSA:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=-BFhLUy6TYs\" target=\"_blank\">Um breve coment\u00e1rio em v\u00eddeo (19 de julho)<\/a><\/p>\n<p><a href=\"https:\/\/futuristgerd.com\/2013\/06\/27\/the-coming-data-wars-the-threat-of-digital-totalitarism-and-why-internet-users-need-to-take-a-stand-now\/\" target=\"_blank\">As guerras de dados que se avizinham, a ascens\u00e3o do totalitarismo digital e a necessidade de os utilizadores da Internet tomarem uma posi\u00e7\u00e3o<\/a> - AGORA (27 de junho de 2013)<\/p>\n<p><a href=\"https:\/\/futuristgerd.com\/2013\/06\/22\/5-reasons-why-the-snowden-nsa-prism-affair-is-a-game-changer-for-the-future-of-the-internet\/\" target=\"_blank\">5 raz\u00f5es pelas quais o caso Snowden \/ NSA \/ PRISM \u00e9, de facto, um divisor de \u00e1guas para o futuro da Internet<\/a> (22 de junho de 2013)<\/p>\n<p><a href=\"https:\/\/futuristgerd.com\/2013\/09\/05\/latest-revelations-on-how-the-nsa-and-other-government-agencies-are-foiling-encryption-plus-a-timely-futurists-conversation-on-privacy-and-security-ross-dawson-and-gerd-leonhard\/\" target=\"_blank\">As \u00faltimas revela\u00e7\u00f5es sobre a forma como a NSA e outras ag\u00eancias governamentais est\u00e3o a destruir a encripta\u00e7\u00e3o, mais uma conversa oportuna com um futurista sobre privacidade e seguran\u00e7a (V\u00eddeo com Ross Dawson e Gerd Leonhard)<\/a><\/p>\n<p><a href=\"https:\/\/blogs.hbr.org\/2013\/07\/a-call-to-boycott-us-tech-plat\/\" target=\"_blank\">O meu guest post na HBR: Um apelo ao boicote das plataformas tecnol\u00f3gicas americanas devido \u00e0 vigil\u00e2ncia PRISM da NSA<\/a> (16 de julho de 2013)<\/p>\n<p><a href=\"https:\/\/futuristgerd.com\/old_lib\/2013\/07\/Ist-es-Zeit-fu\u0308r-einen-Boykott-wegen-PRISM-NSA-Deutsche-Version-Futurist-Author-and-Keynote-Speaker-Gerd-Leonhard.pdf\">\u00c9 altura de fazer um boicote contra a PRISM e a NSA? (Vers\u00e3o alem\u00e3) - Vers\u00e3o alem\u00e3 da pe\u00e7a de boicote Descarregar PDF<\/a><\/p>\n<p><a href=\"https:\/\/futuristgerd.com\/old_lib\/2013\/07\/Portuguese-version-of-HBR-guest-post-Boycott-U.S.-Tech-plataformas-de-tecnologia-norte-americanas-sob-vigila\u0302ncia-das-age\u0302ncias-de-seguranc\u0327a-nacional-dos-US-thanks-to-Flavio-Gut-Futurist-Author-and-Keynote-Speaker-Gerd-Leonhard.pdf\">Vers\u00e3o portuguesa do guest post da HBR Boicote \u00e0s plataformas de tecnologia norte-americanas sob vigil\u00e2ncia das ag\u00eancias de seguran\u00e7a nacional dos EUA (gra\u00e7as a Flavio Gut) PDF download<\/a><\/p>\n<div id='gallery-1' class='gallery galleryid-52565 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-gizmodo.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-gizmodo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-gizmodo-150x150.jpg 150w, https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-gizmodo-128x128.jpg 128w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/08\/nsa-tracking.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/08\/nsa-tracking-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/08\/nsa-tracking-150x150.jpg 150w, https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/08\/nsa-tracking-128x128.jpg 128w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-yes-we-scan.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-yes-we-scan-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-yes-we-scan-150x150.jpg 150w, https:\/\/futuristgerd.com\/wp-content\/uploads\/2013\/07\/prism-yes-we-scan-128x128.jpg 128w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>At\u00e9 \u00e0 pr\u00f3xima <a href=\"https:\/\/www.theguardian.com\/media-network\/2013\/jul\/11\/changing-advertising-summit-2013-programme\" target=\"_blank\">Cimeira de Publicidade do Guardian, ter\u00e7a-feira, em Londres <\/a>(8 de outubro de 2013), onde farei o discurso de encerramento como parte de um painel de discuss\u00e3o para o qual fui convidado <a href=\"https:\/\/www.theguardian.com\/media-network\/media-network-blog\/2013\/oct\/03\/advertisers-digital-bill-of-rights\" target=\"_blank\">contribuir com um post convidado para o The Guardian<\/a> que, por acaso, \u00e9 a minha organiza\u00e7\u00e3o noticiosa de l\u00edngua inglesa favorita e um recurso geral,<\/p>\n<p> ... <a title=\"O meu post como convidado no The Guardian: Porque \u00e9 que os anunciantes devem apoiar uma Carta dos Direitos Digitais a n\u00edvel mundial\" class=\"read-more\" href=\"https:\/\/futuristgerd.com\/pt\/2013\/10\/my-guest-post-at-the-guardian-why-advertisers-should-back-a-global-digital-bill-of-rights\/\" aria-label=\"Ler mais sobre O meu post como convidado no The Guardian: Porque \u00e9 que os anunciantes devem apoiar uma Carta dos Direitos Digitais a n\u00edvel mundial\">Ler mais<\/a><\/p>","protected":false},"author":38,"featured_media":52567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_analytify_skip_tracking":false,"footnotes":""},"categories":[18,136,19,49,66,73,74,8,10],"tags":[214,50,215,184],"class_list":["post-52565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advertising","category-best-of-gerd-leonhard","category-big-data","category-cloud-computing-2","category-communications-marketing","category-gerds-guestposts","category-insights","category-politics-public-policy-government","category-privacy-2","tag-bill-of-digital-rights","tag-datawars","tag-digital-privacy-bill","tag-future-of-advertising","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"_links":{"self":[{"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/posts\/52565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/comments?post=52565"}],"version-history":[{"count":0,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/posts\/52565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/media\/52567"}],"wp:attachment":[{"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/media?parent=52565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/categories?post=52565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futuristgerd.com\/pt\/wp-json\/wp\/v2\/tags?post=52565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}